{"id":2803,"date":"2021-11-24T18:06:00","date_gmt":"2021-11-24T18:06:00","guid":{"rendered":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelle-souvenir-sous-le-ciel-de-gaspe-on-honore-un-pionnier-de-laviation\/"},"modified":"2021-11-24T18:06:00","modified_gmt":"2021-11-24T18:06:00","slug":"nouvelle-souvenir-sous-le-ciel-de-gaspe-on-honore-un-pionnier-de-laviation","status":"publish","type":"nouvelles","link":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/new\/nouvelle-souvenir-sous-le-ciel-de-gaspe-on-honore-un-pionnier-de-laviation\/","title":{"rendered":"Nouvelle-souvenir : Sous le ciel de Gasp\u00e9, on honore un pionnier de l\u2019aviation\u2026"},"content":{"rendered":"<p><em>L\u2019a\u00e9roport de Gasp\u00e9 s\u2019appellera d\u00e9sormais A\u00e9roport Michel-Pouliot de Gasp\u00e9; en effet, la Ville de Gasp\u00e9, qui est propri\u00e9taire et exploitant de l\u2019a\u00e9roport, a d\u00e9cid\u00e9 de le baptiser du nom de cet illustre gasp\u00e9sien, un pionnier de l\u2019aviation dans l\u2019est du Qu\u00e9bec, ancien propri\u00e9taire de la compagnie Air Gasp\u00e9 et chevalier de l\u2019Ordre national du Qu\u00e9bec. Une c\u00e9r\u00e9monie aura lieu dimanche le 12 octobre prochain \u00e0 15h30 \u00e0 l\u2019a\u00e9roport pour marquer cet \u00e9v\u00e9nement.<\/em><\/p>\n<p><strong><a href=\"https:\/\/ville.gaspe.qc.ca\/services-municipaux\/informations-rapides\/aeroport-michel-pouliot-de-gaspe#histoire\" target=\"_blank\" rel=\"noopener\">A\u00e9roport Michel-Pouliot de Gasp\u00e9<\/a><\/strong><\/p>\n<p style=\"text-align: center\"><span style=\"color: #ff6600\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/span><\/p>\n<p>Cet \u00e9v\u00e9nement a eu lieu en 2008\u2026 Le Conseil qu\u00e9b\u00e9cois des a\u00e9roports en a fait la premi\u00e8re nouvelle de la <strong><span style=\"color: #ff6600\">PREMI\u00c8RE \u00c9DITION<\/span><\/strong> du <strong><span style=\"color: #ff6600\">Flash Nouvelles<\/span><\/strong> \u2013 un bulletin s\u2019adressant \u00e0 ses membres\u2026<\/p>\n<p style=\"text-align: center\"><span style=\"color: #ff6600\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/span><\/p>\n<p>Quelque dix ann\u00e9es plus tard\u2026<\/p>\n<p><strong>2018<\/strong> : La Ville de Gasp\u00e9, soucieuse d\u2019offrir un meilleur service aux voyageurs et d\u2019am\u00e9liorer la s\u00e9curit\u00e9 des installations, donne son aval \u00e0 un vaste projet d\u2019agrandissement et de modernisation des infrastructures de l\u2019a\u00e9roport qui comprend notamment l\u2019allongement de la piste\u2026&nbsp;<\/p>\n<p><strong>2019<\/strong>&nbsp;: Monsieur <strong>Michel Pouliot<\/strong>, toujours alerte et\u2026 fort patient, proc\u00e8de en compagnie du maire de Gasp\u00e9, \u00e0 la lev\u00e9e de la premi\u00e8re pellet\u00e9e de terre marquant le d\u00e9but des travaux d\u2019agrandissement de l\u2019a\u00e9roport.<\/p>\n<p style=\"text-align: center\">Ainsi, le 28 novembre 2019, dans la <strong><span style=\"color: #ff6600\">894<sup>e<\/sup> \u00e9dition du Flash Nouvelles<\/span><\/strong>, on soulignait<br \/>\n<a href=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-gaspe-debut-projet-agrandissement\/\" target=\"_blank\" rel=\"noopener\"><strong>le d\u00e9but du projet d&#8217;agrandissement de l&#8217;A\u00e9roport de Gasp\u00e9<\/strong><\/a>.<\/p>\n<p style=\"text-align: center\"><span style=\"color: #ff6600\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/span><\/p>\n<p style=\"text-align: center\"><strong><span style=\"color: #ff6600\">QUESTION<\/span><\/strong><br \/>\n<strong>Depuis combien de temps esp\u00e9rait-on l\u2019allongement de la piste de l\u2019a\u00e9roport?<\/strong><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 10pt\">(La r\u00e9ponse est dans l&#8217;article&#8230; Vous ne la trouvez pas?<br \/>\nDans ce cas, ne ratez pas le Flash&nbsp;Nouvelles du 6 janvier 2022!)<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","class_list":["post-2803","nouvelles","type-nouvelles","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nouvelle-souvenir : Sous le ciel de Gasp\u00e9, on honore un pionnier de l\u2019aviation\u2026 - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelle-souvenir-sous-le-ciel-de-gaspe-on-honore-un-pionnier-de-laviation\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvelle-souvenir : Sous le ciel de Gasp\u00e9, on honore un pionnier de l\u2019aviation\u2026 - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\" \/>\n<meta property=\"og:description\" content=\"L\u2019a\u00e9roport de Gasp\u00e9 s\u2019appellera d\u00e9sormais A\u00e9roport Michel-Pouliot de Gasp\u00e9; en effet, la Ville de Gasp\u00e9, qui est propri\u00e9taire et exploitant de l\u2019a\u00e9roport, a d\u00e9cid\u00e9 de le baptiser du nom de cet illustre gasp\u00e9sien, un pionnier de l\u2019aviation dans l\u2019est du Qu\u00e9bec, ancien propri\u00e9taire de la compagnie Air Gasp\u00e9 et chevalier...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelle-souvenir-sous-le-ciel-de-gaspe-on-honore-un-pionnier-de-laviation\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelle-souvenir-sous-le-ciel-de-gaspe-on-honore-un-pionnier-de-laviation\/\",\"url\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelle-souvenir-sous-le-ciel-de-gaspe-on-honore-un-pionnier-de-laviation\/\",\"name\":\"Nouvelle-souvenir : Sous le ciel de Gasp\u00e9, on honore un pionnier de l\u2019aviation\u2026 - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\",\"isPartOf\":{\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/#website\"},\"datePublished\":\"2021-11-24T18:06:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelle-souvenir-sous-le-ciel-de-gaspe-on-honore-un-pionnier-de-laviation\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelle-souvenir-sous-le-ciel-de-gaspe-on-honore-un-pionnier-de-laviation\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelle-souvenir-sous-le-ciel-de-gaspe-on-honore-un-pionnier-de-laviation\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/reseauquebecoisdesaeroports.ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelle-souvenir : Sous le ciel de Gasp\u00e9, on honore un pionnier de l\u2019aviation\u2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/#website\",\"url\":\"https:\/\/reseauquebecoisdesaeroports.ca\/\",\"name\":\"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/reseauquebecoisdesaeroports.ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouvelle-souvenir : Sous le ciel de Gasp\u00e9, on honore un pionnier de l\u2019aviation\u2026 - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelle-souvenir-sous-le-ciel-de-gaspe-on-honore-un-pionnier-de-laviation\/","og_locale":"en_US","og_type":"article","og_title":"Nouvelle-souvenir : Sous le ciel de Gasp\u00e9, on honore un pionnier de l\u2019aviation\u2026 - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","og_description":"L\u2019a\u00e9roport de Gasp\u00e9 s\u2019appellera d\u00e9sormais A\u00e9roport Michel-Pouliot de Gasp\u00e9; en effet, la Ville de Gasp\u00e9, qui est propri\u00e9taire et exploitant de l\u2019a\u00e9roport, a d\u00e9cid\u00e9 de le baptiser du nom de cet illustre gasp\u00e9sien, un pionnier de l\u2019aviation dans l\u2019est du Qu\u00e9bec, ancien propri\u00e9taire de la compagnie Air Gasp\u00e9 et chevalier...","og_url":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelle-souvenir-sous-le-ciel-de-gaspe-on-honore-un-pionnier-de-laviation\/","og_site_name":"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelle-souvenir-sous-le-ciel-de-gaspe-on-honore-un-pionnier-de-laviation\/","url":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelle-souvenir-sous-le-ciel-de-gaspe-on-honore-un-pionnier-de-laviation\/","name":"Nouvelle-souvenir : Sous le ciel de Gasp\u00e9, on honore un pionnier de l\u2019aviation\u2026 - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","isPartOf":{"@id":"https:\/\/reseauquebecoisdesaeroports.ca\/#website"},"datePublished":"2021-11-24T18:06:00+00:00","breadcrumb":{"@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelle-souvenir-sous-le-ciel-de-gaspe-on-honore-un-pionnier-de-laviation\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelle-souvenir-sous-le-ciel-de-gaspe-on-honore-un-pionnier-de-laviation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelle-souvenir-sous-le-ciel-de-gaspe-on-honore-un-pionnier-de-laviation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/reseauquebecoisdesaeroports.ca\/"},{"@type":"ListItem","position":2,"name":"Nouvelle-souvenir : Sous le ciel de Gasp\u00e9, on honore un pionnier de l\u2019aviation\u2026"}]},{"@type":"WebSite","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/#website","url":"https:\/\/reseauquebecoisdesaeroports.ca\/","name":"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reseauquebecoisdesaeroports.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"}]}},"_links":{"self":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/nouvelles\/2803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/nouvelles"}],"about":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/types\/nouvelles"}],"author":[{"embeddable":true,"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/media?parent=2803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}