{"id":2818,"date":"2021-12-08T18:08:00","date_gmt":"2021-12-08T18:08:49","guid":{"rendered":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelles-souvenirs-dans-le-ciel-des-ailes-moins-polluantes\/"},"modified":"2021-12-08T18:08:00","modified_gmt":"2021-12-08T18:08:49","slug":"nouvelles-souvenirs-dans-le-ciel-des-ailes-moins-polluantes","status":"publish","type":"nouvelles","link":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/new\/nouvelles-souvenirs-dans-le-ciel-des-ailes-moins-polluantes\/","title":{"rendered":"Nouvelles-souvenirs \u2013 Dans le ciel, des ailes moins polluantes\u2026"},"content":{"rendered":"<p>L\u2019industrie a\u00e9rienne multiplie les efforts pour r\u00e9duire son impact sur l\u2019environnement \u2013 un sujet chaud! On mise entre autres sur les biocarburants et sur l\u2019avion \u00e9lectrique\u2026&nbsp;<\/p>\n<p><strong>BIOCARBURANTS<\/strong><\/p>\n<p><strong>2018 \u2013 <span style=\"color: #ff6600\">806<sup>e<\/sup> \u00e9dition du Flash Nouvelles&nbsp;<\/span>: &nbsp;<a href=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/iata-nouveaux-carburants\/\" target=\"_blank\" rel=\"noopener\">L\u2019IATA souhaiterait qu\u2019en 2025, un milliard de passagers voyagent sur des vols propuls\u00e9s par un m\u00e9lange de carbur\u00e9acteur et de carburant d\u2019aviation durable\u2026<\/a><\/strong> Rappelons que d\u00e8s <strong>2008<\/strong>, un Boeing 747 de Virgin Atlantic a effectu\u00e9 un vol de Londres \u00e0 Amsterdam avec du carburant d\u2019aviation durable alimentant un de ses moteurs\u2026&nbsp;<\/p>\n<p><strong>2018 \u2013 <span style=\"color: #ff6600\">834<sup>e<\/sup> \u00e9dition du Flash Nouvelles&nbsp;<\/span>: <\/strong>Heureusement, <strong><a href=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/united-airlines-biocarburant-quebecois\/\" target=\"_blank\" rel=\"noopener\">la moutarde ne nous monte pas toujours au nez\u2026&nbsp;<\/a><\/strong><\/p>\n<p><strong>2021 \u2013 <\/strong>Il semble que tout baigne dans l\u2019huile comme dans cette <a href=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/biocarburant-aerien-paris-montreal-avec-vieille-huile-friture\/\" target=\"_blank\" rel=\"noopener\"><strong>nouvelle<\/strong> <\/a>du <span style=\"color: #ff6600\"><strong>Flash Nouvelles 969&nbsp;<\/strong><\/span><span style=\"color: #ff9900\"><span style=\"color: #000000\">ou dans cette <strong><a href=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/shell-souhaite-produire-biocarburant-aviation\/\" target=\"_blank\" rel=\"noopener\">autre<\/a><\/strong> parue dans la <span style=\"color: #ff6600\"><strong>986<sup>e<\/sup> \u00e9dition du Flash Nouvelles<\/strong><\/span>!<\/span><\/span><\/p>\n<p style=\"text-align: center\"><span style=\"color: #ff6600\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"color: #ff6600\"><strong>QUESTION<\/strong><\/span><br \/>\n<strong>\u00c0 combien \u00e9value-t-on les \u00e9missions mondiales de gaz \u00e0 effet de serre du secteur a\u00e9rien? 3 %? 10 %? ou 17 %?<\/strong><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 10pt\">(La r\u00e9ponse est dans le lien pr\u00e9c\u00e9dent et sera dans le Flash Nouvelles du 6 janvier 2022!)<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"color: #ff6600\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/span><\/p>\n<p><strong>AVION \u00c9LECTRIQUE<\/strong><\/p>\n<p>Les constructeurs a\u00e9ronautiques y travaillent mais l\u2019\u00e9lectrification des avions pose de grands d\u00e9fis\u2026<\/p>\n<p>Ainsi, dans <span style=\"color: #ff9900\"><span style=\"color: #000000\">la<\/span><\/span><strong><span style=\"color: #ff9900\"> <span style=\"color: #ff6600\">811<sup>e<\/sup> \u00e9dition du Flash Nouvelles<\/span><\/span><\/strong> en <strong>2018<\/strong>, on se demande <strong><a href=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/avion-electrique-article-de-presse\/\" target=\"_blank\" rel=\"noopener\">si l\u2019avion \u00e9lectrique pourra faire face \u00e0 des conditions glaciales, des vents forts\u2026<\/a><\/strong><\/p>\n<p>et en <strong>2020<\/strong>, dans <strong><span style=\"color: #ff9900\"><strong><span style=\"color: #000000\">le<\/span><\/strong> <span style=\"color: #ff6600\">Flash Nouvelles 919<\/span><\/span><\/strong>, on parle de <strong><a href=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/defi-avions-de-ligne-electriques\/\" target=\"_blank\" rel=\"noopener\">la construction des batteries \u00e9lectriques qui doivent \u00eatre assez puissantes et l\u00e9g\u00e8res\u2026<\/a>&nbsp;<\/strong><\/p>\n<p>Mais tous les espoirs sont permis!<\/p>\n<p><strong>2021<\/strong> \u2013 <span style=\"color: #ff6600\"><strong>Flash Nouvelles 985<\/strong><\/span> &#8211; Hydravions, avion 9 places, taxi urbain 2 places \u2013 <strong><a href=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/innovation-pas-en-avant-avion-electrique\/\" target=\"_blank\" rel=\"noopener\">premiers achats d\u2019avions \u00e9lectriques par des compagnies a\u00e9riennes \u00e9tablies\u2026<\/a> &nbsp;<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","class_list":["post-2818","nouvelles","type-nouvelles","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nouvelles-souvenirs \u2013 Dans le ciel, des ailes moins polluantes\u2026 - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelles-souvenirs-dans-le-ciel-des-ailes-moins-polluantes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvelles-souvenirs \u2013 Dans le ciel, des ailes moins polluantes\u2026 - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\" \/>\n<meta property=\"og:description\" content=\"L\u2019industrie a\u00e9rienne multiplie les efforts pour r\u00e9duire son impact sur l\u2019environnement \u2013 un sujet chaud! On mise entre autres sur les biocarburants et sur l\u2019avion \u00e9lectrique\u2026&nbsp; BIOCARBURANTS 2018 \u2013 806e \u00e9dition du Flash Nouvelles&nbsp;: &nbsp;L\u2019IATA souhaiterait qu\u2019en 2025, un milliard de passagers voyagent sur des vols propuls\u00e9s par un m\u00e9lange...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelles-souvenirs-dans-le-ciel-des-ailes-moins-polluantes\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelles-souvenirs-dans-le-ciel-des-ailes-moins-polluantes\/\",\"url\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelles-souvenirs-dans-le-ciel-des-ailes-moins-polluantes\/\",\"name\":\"Nouvelles-souvenirs \u2013 Dans le ciel, des ailes moins polluantes\u2026 - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\",\"isPartOf\":{\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/#website\"},\"datePublished\":\"2021-12-08T18:08:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelles-souvenirs-dans-le-ciel-des-ailes-moins-polluantes\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelles-souvenirs-dans-le-ciel-des-ailes-moins-polluantes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelles-souvenirs-dans-le-ciel-des-ailes-moins-polluantes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/reseauquebecoisdesaeroports.ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles-souvenirs \u2013 Dans le ciel, des ailes moins polluantes\u2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/#website\",\"url\":\"https:\/\/reseauquebecoisdesaeroports.ca\/\",\"name\":\"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/reseauquebecoisdesaeroports.ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouvelles-souvenirs \u2013 Dans le ciel, des ailes moins polluantes\u2026 - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelles-souvenirs-dans-le-ciel-des-ailes-moins-polluantes\/","og_locale":"en_US","og_type":"article","og_title":"Nouvelles-souvenirs \u2013 Dans le ciel, des ailes moins polluantes\u2026 - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","og_description":"L\u2019industrie a\u00e9rienne multiplie les efforts pour r\u00e9duire son impact sur l\u2019environnement \u2013 un sujet chaud! On mise entre autres sur les biocarburants et sur l\u2019avion \u00e9lectrique\u2026&nbsp; BIOCARBURANTS 2018 \u2013 806e \u00e9dition du Flash Nouvelles&nbsp;: &nbsp;L\u2019IATA souhaiterait qu\u2019en 2025, un milliard de passagers voyagent sur des vols propuls\u00e9s par un m\u00e9lange...","og_url":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelles-souvenirs-dans-le-ciel-des-ailes-moins-polluantes\/","og_site_name":"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelles-souvenirs-dans-le-ciel-des-ailes-moins-polluantes\/","url":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelles-souvenirs-dans-le-ciel-des-ailes-moins-polluantes\/","name":"Nouvelles-souvenirs \u2013 Dans le ciel, des ailes moins polluantes\u2026 - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","isPartOf":{"@id":"https:\/\/reseauquebecoisdesaeroports.ca\/#website"},"datePublished":"2021-12-08T18:08:49+00:00","breadcrumb":{"@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelles-souvenirs-dans-le-ciel-des-ailes-moins-polluantes\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelles-souvenirs-dans-le-ciel-des-ailes-moins-polluantes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nouvelles-souvenirs-dans-le-ciel-des-ailes-moins-polluantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/reseauquebecoisdesaeroports.ca\/"},{"@type":"ListItem","position":2,"name":"Nouvelles-souvenirs \u2013 Dans le ciel, des ailes moins polluantes\u2026"}]},{"@type":"WebSite","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/#website","url":"https:\/\/reseauquebecoisdesaeroports.ca\/","name":"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reseauquebecoisdesaeroports.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"}]}},"_links":{"self":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/nouvelles\/2818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/nouvelles"}],"about":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/types\/nouvelles"}],"author":[{"embeddable":true,"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/media?parent=2818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}