{"id":2820,"date":"2021-12-15T18:00:00","date_gmt":"2021-12-15T18:00:51","guid":{"rendered":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-quebec-test-rapide-des-le-15-decembre-sur-site-aeroport\/"},"modified":"2021-12-15T18:00:00","modified_gmt":"2021-12-15T18:00:51","slug":"aeroport-quebec-test-rapide-des-le-15-decembre-sur-site-aeroport","status":"publish","type":"nouvelles","link":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/new\/aeroport-quebec-test-rapide-des-le-15-decembre-sur-site-aeroport\/","title":{"rendered":"A\u00e9roport de Qu\u00e9bec : un test rapide d\u00e8s le 15 d\u00e9cembre sur le site de l\u2019a\u00e9roport"},"content":{"rendered":"<p>Les voyageurs, qui ont besoin d\u2019un test antig\u00e9nique COVID-19 avant de se d\u00e9placer, pourront faire un arr\u00eat sur le site m\u00eame de l\u2019a\u00e9roport international Jean-Lesage (YQB) pour s\u2019assurer qu\u2019ils ne sont pas porteurs du virus.&nbsp;<\/p>\n<p>Un centre de d\u00e9pistage sera am\u00e9nag\u00e9 au Complexe Capitale H\u00e9licopt\u00e8re, o\u00f9 les premiers clients sont attendus \u00e0 compter du mercredi 15 d\u00e9cembre. Le r\u00e9sultat du test sera connu en moins de 20 minutes.&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","class_list":["post-2820","nouvelles","type-nouvelles","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A\u00e9roport de Qu\u00e9bec : un test rapide d\u00e8s le 15 d\u00e9cembre sur le site de l\u2019a\u00e9roport - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-quebec-test-rapide-des-le-15-decembre-sur-site-aeroport\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A\u00e9roport de Qu\u00e9bec : un test rapide d\u00e8s le 15 d\u00e9cembre sur le site de l\u2019a\u00e9roport - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\" \/>\n<meta property=\"og:description\" content=\"Les voyageurs, qui ont besoin d\u2019un test antig\u00e9nique COVID-19 avant de se d\u00e9placer, pourront faire un arr\u00eat sur le site m\u00eame de l\u2019a\u00e9roport international Jean-Lesage (YQB) pour s\u2019assurer qu\u2019ils ne sont pas porteurs du virus.&nbsp; Un centre de d\u00e9pistage sera am\u00e9nag\u00e9 au Complexe Capitale H\u00e9licopt\u00e8re, o\u00f9 les premiers clients sont...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-quebec-test-rapide-des-le-15-decembre-sur-site-aeroport\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-quebec-test-rapide-des-le-15-decembre-sur-site-aeroport\/\",\"url\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-quebec-test-rapide-des-le-15-decembre-sur-site-aeroport\/\",\"name\":\"A\u00e9roport de Qu\u00e9bec : un test rapide d\u00e8s le 15 d\u00e9cembre sur le site de l\u2019a\u00e9roport - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\",\"isPartOf\":{\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/#website\"},\"datePublished\":\"2021-12-15T18:00:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-quebec-test-rapide-des-le-15-decembre-sur-site-aeroport\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-quebec-test-rapide-des-le-15-decembre-sur-site-aeroport\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-quebec-test-rapide-des-le-15-decembre-sur-site-aeroport\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/reseauquebecoisdesaeroports.ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A\u00e9roport de Qu\u00e9bec : un test rapide d\u00e8s le 15 d\u00e9cembre sur le site de l\u2019a\u00e9roport\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/#website\",\"url\":\"https:\/\/reseauquebecoisdesaeroports.ca\/\",\"name\":\"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/reseauquebecoisdesaeroports.ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A\u00e9roport de Qu\u00e9bec : un test rapide d\u00e8s le 15 d\u00e9cembre sur le site de l\u2019a\u00e9roport - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-quebec-test-rapide-des-le-15-decembre-sur-site-aeroport\/","og_locale":"en_US","og_type":"article","og_title":"A\u00e9roport de Qu\u00e9bec : un test rapide d\u00e8s le 15 d\u00e9cembre sur le site de l\u2019a\u00e9roport - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","og_description":"Les voyageurs, qui ont besoin d\u2019un test antig\u00e9nique COVID-19 avant de se d\u00e9placer, pourront faire un arr\u00eat sur le site m\u00eame de l\u2019a\u00e9roport international Jean-Lesage (YQB) pour s\u2019assurer qu\u2019ils ne sont pas porteurs du virus.&nbsp; Un centre de d\u00e9pistage sera am\u00e9nag\u00e9 au Complexe Capitale H\u00e9licopt\u00e8re, o\u00f9 les premiers clients sont...","og_url":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-quebec-test-rapide-des-le-15-decembre-sur-site-aeroport\/","og_site_name":"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-quebec-test-rapide-des-le-15-decembre-sur-site-aeroport\/","url":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-quebec-test-rapide-des-le-15-decembre-sur-site-aeroport\/","name":"A\u00e9roport de Qu\u00e9bec : un test rapide d\u00e8s le 15 d\u00e9cembre sur le site de l\u2019a\u00e9roport - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","isPartOf":{"@id":"https:\/\/reseauquebecoisdesaeroports.ca\/#website"},"datePublished":"2021-12-15T18:00:51+00:00","breadcrumb":{"@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-quebec-test-rapide-des-le-15-decembre-sur-site-aeroport\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-quebec-test-rapide-des-le-15-decembre-sur-site-aeroport\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-quebec-test-rapide-des-le-15-decembre-sur-site-aeroport\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/reseauquebecoisdesaeroports.ca\/"},{"@type":"ListItem","position":2,"name":"A\u00e9roport de Qu\u00e9bec : un test rapide d\u00e8s le 15 d\u00e9cembre sur le site de l\u2019a\u00e9roport"}]},{"@type":"WebSite","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/#website","url":"https:\/\/reseauquebecoisdesaeroports.ca\/","name":"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reseauquebecoisdesaeroports.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"}]}},"_links":{"self":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/nouvelles\/2820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/nouvelles"}],"about":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/types\/nouvelles"}],"author":[{"embeddable":true,"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/media?parent=2820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}