{"id":2862,"date":"2022-02-09T18:01:00","date_gmt":"2022-02-09T18:01:00","guid":{"rendered":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nav-canada-rouyn-noranda-toujours-sur-ses-gardes\/"},"modified":"2022-02-09T18:01:00","modified_gmt":"2022-02-09T18:01:00","slug":"nav-canada-rouyn-noranda-toujours-sur-ses-gardes","status":"publish","type":"nouvelles","link":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/new\/nav-canada-rouyn-noranda-toujours-sur-ses-gardes\/","title":{"rendered":"NAV CANADA : Rouyn-Noranda toujours sur ses gardes"},"content":{"rendered":"<p>La Ville de Rouyn-Noranda, pour une \u00e9ni\u00e8me fois, se munit de l&#8217;expertise de TACT Intelligence-conseil afin d&#8217;\u00eatre \u00e9paul\u00e9e dans son combat contre NAV CANADA.<\/p>\n<p>Les \u00e9lus octroient un contrat additionnel de 10&nbsp;000&nbsp;$ pour les services de la firme. La Ville a besoin d&#8217;un coup de main notamment au niveau des d\u00e9marches et strat\u00e9gies lors de ses repr\u00e9sentations aupr\u00e8s du gouvernement.<\/p>\n<p>Le souhait de NAV CANADA est de r\u00e9duire les services de nuit \u00e0 l&#8217;a\u00e9roport de Rouyn-Noranda, en implantant plut\u00f4t un syst\u00e8me automatis\u00e9 nomm\u00e9 AWOS.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","class_list":["post-2862","nouvelles","type-nouvelles","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NAV CANADA : Rouyn-Noranda toujours sur ses gardes - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nav-canada-rouyn-noranda-toujours-sur-ses-gardes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NAV CANADA : Rouyn-Noranda toujours sur ses gardes - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\" \/>\n<meta property=\"og:description\" content=\"La Ville de Rouyn-Noranda, pour une \u00e9ni\u00e8me fois, se munit de l&#8217;expertise de TACT Intelligence-conseil afin d&#8217;\u00eatre \u00e9paul\u00e9e dans son combat contre NAV CANADA. Les \u00e9lus octroient un contrat additionnel de 10&nbsp;000&nbsp;$ pour les services de la firme. La Ville a besoin d&#8217;un coup de main notamment au niveau des...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nav-canada-rouyn-noranda-toujours-sur-ses-gardes\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nav-canada-rouyn-noranda-toujours-sur-ses-gardes\/\",\"url\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nav-canada-rouyn-noranda-toujours-sur-ses-gardes\/\",\"name\":\"NAV CANADA : Rouyn-Noranda toujours sur ses gardes - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\",\"isPartOf\":{\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/#website\"},\"datePublished\":\"2022-02-09T18:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nav-canada-rouyn-noranda-toujours-sur-ses-gardes\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nav-canada-rouyn-noranda-toujours-sur-ses-gardes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nav-canada-rouyn-noranda-toujours-sur-ses-gardes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/reseauquebecoisdesaeroports.ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NAV CANADA : Rouyn-Noranda toujours sur ses gardes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/#website\",\"url\":\"https:\/\/reseauquebecoisdesaeroports.ca\/\",\"name\":\"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/reseauquebecoisdesaeroports.ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NAV CANADA : Rouyn-Noranda toujours sur ses gardes - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nav-canada-rouyn-noranda-toujours-sur-ses-gardes\/","og_locale":"en_US","og_type":"article","og_title":"NAV CANADA : Rouyn-Noranda toujours sur ses gardes - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","og_description":"La Ville de Rouyn-Noranda, pour une \u00e9ni\u00e8me fois, se munit de l&#8217;expertise de TACT Intelligence-conseil afin d&#8217;\u00eatre \u00e9paul\u00e9e dans son combat contre NAV CANADA. Les \u00e9lus octroient un contrat additionnel de 10&nbsp;000&nbsp;$ pour les services de la firme. La Ville a besoin d&#8217;un coup de main notamment au niveau des...","og_url":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nav-canada-rouyn-noranda-toujours-sur-ses-gardes\/","og_site_name":"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nav-canada-rouyn-noranda-toujours-sur-ses-gardes\/","url":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nav-canada-rouyn-noranda-toujours-sur-ses-gardes\/","name":"NAV CANADA : Rouyn-Noranda toujours sur ses gardes - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","isPartOf":{"@id":"https:\/\/reseauquebecoisdesaeroports.ca\/#website"},"datePublished":"2022-02-09T18:01:00+00:00","breadcrumb":{"@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nav-canada-rouyn-noranda-toujours-sur-ses-gardes\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reseauquebecoisdesaeroports.ca\/new\/nav-canada-rouyn-noranda-toujours-sur-ses-gardes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/nav-canada-rouyn-noranda-toujours-sur-ses-gardes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/reseauquebecoisdesaeroports.ca\/"},{"@type":"ListItem","position":2,"name":"NAV CANADA : Rouyn-Noranda toujours sur ses gardes"}]},{"@type":"WebSite","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/#website","url":"https:\/\/reseauquebecoisdesaeroports.ca\/","name":"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reseauquebecoisdesaeroports.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"}]}},"_links":{"self":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/nouvelles\/2862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/nouvelles"}],"about":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/types\/nouvelles"}],"author":[{"embeddable":true,"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/media?parent=2862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}