{"id":2864,"date":"2022-02-09T18:03:00","date_gmt":"2022-02-09T18:03:18","guid":{"rendered":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-la-sarre-quebec-verse-110-000-mise-niveau-installations\/"},"modified":"2022-02-09T18:03:00","modified_gmt":"2022-02-09T18:03:18","slug":"aeroport-la-sarre-quebec-verse-110-000-mise-niveau-installations","status":"publish","type":"nouvelles","link":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/new\/aeroport-la-sarre-quebec-verse-110-000-mise-niveau-installations\/","title":{"rendered":"A\u00e9roport de La Sarre : Qu\u00e9bec verse 110 000 $ pour la mise \u00e0 niveau des installations"},"content":{"rendered":"<p>Le gouvernement du Qu\u00e9bec octroie pr\u00e8s de 110 000 $ pour le remplacement des r\u00e9servoirs de pompage \u00e0 l\u2019a\u00e9roport de La Sarre. Un soutien financier qui permet \u00e0 la Ville de La Sarre de finaliser la mise \u00e0 niveau des installations a\u00e9roportuaires.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","class_list":["post-2864","nouvelles","type-nouvelles","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A\u00e9roport de La Sarre : Qu\u00e9bec verse 110 000 $ pour la mise \u00e0 niveau des installations - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-la-sarre-quebec-verse-110-000-mise-niveau-installations\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A\u00e9roport de La Sarre : Qu\u00e9bec verse 110 000 $ pour la mise \u00e0 niveau des installations - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\" \/>\n<meta property=\"og:description\" content=\"Le gouvernement du Qu\u00e9bec octroie pr\u00e8s de 110 000 $ pour le remplacement des r\u00e9servoirs de pompage \u00e0 l\u2019a\u00e9roport de La Sarre. Un soutien financier qui permet \u00e0 la Ville de La Sarre de finaliser la mise \u00e0 niveau des installations a\u00e9roportuaires.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-la-sarre-quebec-verse-110-000-mise-niveau-installations\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-la-sarre-quebec-verse-110-000-mise-niveau-installations\/\",\"url\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-la-sarre-quebec-verse-110-000-mise-niveau-installations\/\",\"name\":\"A\u00e9roport de La Sarre : Qu\u00e9bec verse 110 000 $ pour la mise \u00e0 niveau des installations - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\",\"isPartOf\":{\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/#website\"},\"datePublished\":\"2022-02-09T18:03:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-la-sarre-quebec-verse-110-000-mise-niveau-installations\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-la-sarre-quebec-verse-110-000-mise-niveau-installations\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-la-sarre-quebec-verse-110-000-mise-niveau-installations\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/reseauquebecoisdesaeroports.ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A\u00e9roport de La Sarre : Qu\u00e9bec verse 110 000 $ pour la mise \u00e0 niveau des installations\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/#website\",\"url\":\"https:\/\/reseauquebecoisdesaeroports.ca\/\",\"name\":\"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/reseauquebecoisdesaeroports.ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A\u00e9roport de La Sarre : Qu\u00e9bec verse 110 000 $ pour la mise \u00e0 niveau des installations - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-la-sarre-quebec-verse-110-000-mise-niveau-installations\/","og_locale":"en_US","og_type":"article","og_title":"A\u00e9roport de La Sarre : Qu\u00e9bec verse 110 000 $ pour la mise \u00e0 niveau des installations - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","og_description":"Le gouvernement du Qu\u00e9bec octroie pr\u00e8s de 110 000 $ pour le remplacement des r\u00e9servoirs de pompage \u00e0 l\u2019a\u00e9roport de La Sarre. Un soutien financier qui permet \u00e0 la Ville de La Sarre de finaliser la mise \u00e0 niveau des installations a\u00e9roportuaires.","og_url":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-la-sarre-quebec-verse-110-000-mise-niveau-installations\/","og_site_name":"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-la-sarre-quebec-verse-110-000-mise-niveau-installations\/","url":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-la-sarre-quebec-verse-110-000-mise-niveau-installations\/","name":"A\u00e9roport de La Sarre : Qu\u00e9bec verse 110 000 $ pour la mise \u00e0 niveau des installations - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","isPartOf":{"@id":"https:\/\/reseauquebecoisdesaeroports.ca\/#website"},"datePublished":"2022-02-09T18:03:18+00:00","breadcrumb":{"@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-la-sarre-quebec-verse-110-000-mise-niveau-installations\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-la-sarre-quebec-verse-110-000-mise-niveau-installations\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-la-sarre-quebec-verse-110-000-mise-niveau-installations\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/reseauquebecoisdesaeroports.ca\/"},{"@type":"ListItem","position":2,"name":"A\u00e9roport de La Sarre : Qu\u00e9bec verse 110 000 $ pour la mise \u00e0 niveau des installations"}]},{"@type":"WebSite","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/#website","url":"https:\/\/reseauquebecoisdesaeroports.ca\/","name":"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reseauquebecoisdesaeroports.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"}]}},"_links":{"self":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/nouvelles\/2864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/nouvelles"}],"about":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/types\/nouvelles"}],"author":[{"embeddable":true,"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/media?parent=2864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}