{"id":2876,"date":"2022-03-02T18:00:00","date_gmt":"2022-03-02T18:00:42","guid":{"rendered":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-de-matane-le-dossier-de-la-construction-de-laerogare-progresse\/"},"modified":"2022-03-02T18:00:00","modified_gmt":"2022-03-02T18:00:42","slug":"aeroport-de-matane-le-dossier-de-la-construction-de-laerogare-progresse","status":"publish","type":"nouvelles","link":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/new\/aeroport-de-matane-le-dossier-de-la-construction-de-laerogare-progresse\/","title":{"rendered":"A\u00e9roport de Matane : le dossier de la construction de l\u2019a\u00e9rogare progresse"},"content":{"rendered":"<p>La Ville de Matane avance dans le dossier de la construction de l\u2019a\u00e9rogare Jean\u2011Marc\u2011Lefran\u00e7ois \u00e0 l\u2019a\u00e9roport Russel-Burnett, dans le secteur de Petit-Matane. Comme la r\u00e9fection de la piste d\u2019atterrissage est termin\u00e9e, la municipalit\u00e9 a accord\u00e9 deux contrats \u00e0 des firmes sp\u00e9cialis\u00e9es pour les services professionnels en ing\u00e9nierie et architecture.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","class_list":["post-2876","nouvelles","type-nouvelles","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A\u00e9roport de Matane : le dossier de la construction de l\u2019a\u00e9rogare progresse - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-de-matane-le-dossier-de-la-construction-de-laerogare-progresse\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A\u00e9roport de Matane : le dossier de la construction de l\u2019a\u00e9rogare progresse - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\" \/>\n<meta property=\"og:description\" content=\"La Ville de Matane avance dans le dossier de la construction de l\u2019a\u00e9rogare Jean\u2011Marc\u2011Lefran\u00e7ois \u00e0 l\u2019a\u00e9roport Russel-Burnett, dans le secteur de Petit-Matane. Comme la r\u00e9fection de la piste d\u2019atterrissage est termin\u00e9e, la municipalit\u00e9 a accord\u00e9 deux contrats \u00e0 des firmes sp\u00e9cialis\u00e9es pour les services professionnels en ing\u00e9nierie et architecture.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-de-matane-le-dossier-de-la-construction-de-laerogare-progresse\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-de-matane-le-dossier-de-la-construction-de-laerogare-progresse\/\",\"url\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-de-matane-le-dossier-de-la-construction-de-laerogare-progresse\/\",\"name\":\"A\u00e9roport de Matane : le dossier de la construction de l\u2019a\u00e9rogare progresse - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\",\"isPartOf\":{\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/#website\"},\"datePublished\":\"2022-03-02T18:00:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-de-matane-le-dossier-de-la-construction-de-laerogare-progresse\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-de-matane-le-dossier-de-la-construction-de-laerogare-progresse\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-de-matane-le-dossier-de-la-construction-de-laerogare-progresse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/reseauquebecoisdesaeroports.ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A\u00e9roport de Matane : le dossier de la construction de l\u2019a\u00e9rogare progresse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/#website\",\"url\":\"https:\/\/reseauquebecoisdesaeroports.ca\/\",\"name\":\"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/reseauquebecoisdesaeroports.ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A\u00e9roport de Matane : le dossier de la construction de l\u2019a\u00e9rogare progresse - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-de-matane-le-dossier-de-la-construction-de-laerogare-progresse\/","og_locale":"en_US","og_type":"article","og_title":"A\u00e9roport de Matane : le dossier de la construction de l\u2019a\u00e9rogare progresse - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","og_description":"La Ville de Matane avance dans le dossier de la construction de l\u2019a\u00e9rogare Jean\u2011Marc\u2011Lefran\u00e7ois \u00e0 l\u2019a\u00e9roport Russel-Burnett, dans le secteur de Petit-Matane. Comme la r\u00e9fection de la piste d\u2019atterrissage est termin\u00e9e, la municipalit\u00e9 a accord\u00e9 deux contrats \u00e0 des firmes sp\u00e9cialis\u00e9es pour les services professionnels en ing\u00e9nierie et architecture.","og_url":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-de-matane-le-dossier-de-la-construction-de-laerogare-progresse\/","og_site_name":"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-de-matane-le-dossier-de-la-construction-de-laerogare-progresse\/","url":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-de-matane-le-dossier-de-la-construction-de-laerogare-progresse\/","name":"A\u00e9roport de Matane : le dossier de la construction de l\u2019a\u00e9rogare progresse - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","isPartOf":{"@id":"https:\/\/reseauquebecoisdesaeroports.ca\/#website"},"datePublished":"2022-03-02T18:00:42+00:00","breadcrumb":{"@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-de-matane-le-dossier-de-la-construction-de-laerogare-progresse\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-de-matane-le-dossier-de-la-construction-de-laerogare-progresse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/aeroport-de-matane-le-dossier-de-la-construction-de-laerogare-progresse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/reseauquebecoisdesaeroports.ca\/"},{"@type":"ListItem","position":2,"name":"A\u00e9roport de Matane : le dossier de la construction de l\u2019a\u00e9rogare progresse"}]},{"@type":"WebSite","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/#website","url":"https:\/\/reseauquebecoisdesaeroports.ca\/","name":"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reseauquebecoisdesaeroports.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"}]}},"_links":{"self":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/nouvelles\/2876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/nouvelles"}],"about":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/types\/nouvelles"}],"author":[{"embeddable":true,"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/media?parent=2876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}