{"id":2877,"date":"2022-03-02T18:01:00","date_gmt":"2022-03-02T18:01:51","guid":{"rendered":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/coop-air-lac-saint-jean-croit-toujours-decollage-projet\/"},"modified":"2022-03-02T18:01:00","modified_gmt":"2022-03-02T18:01:51","slug":"coop-air-lac-saint-jean-croit-toujours-decollage-projet","status":"publish","type":"nouvelles","link":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/new\/coop-air-lac-saint-jean-croit-toujours-decollage-projet\/","title":{"rendered":"Transport r\u00e9gional : la coop Air du Lac-Saint-Jean croit toujours au d\u00e9collage de son projet"},"content":{"rendered":"<p>Malgr\u00e9 la pand\u00e9mie et l\u2019attente pour le d\u00e9voilement de la strat\u00e9gie en transport a\u00e9rien r\u00e9gional du ministre Fran\u00e7ois Bonnardel, la coop Air du Lac-Saint-Jean a poursuivi son travail afin d\u2019\u00eatre pr\u00eate lorsque les gens pourront voyager plus librement.<\/p>\n<p>L\u2019objectif demeure le m\u00eame qu\u2019en novembre 2019, lors de son d\u00e9voilement : offrir des vols Alma-Roberval-Montr\u00e9al. Au d\u00e9part, l\u2019organisme croyait en offrir au d\u00e9but de 2020. \u00ab Notre mod\u00e8le est simple, donc il devrait int\u00e9resser le gouvernement \u00bb, r\u00e9it\u00e8re en entrevue le pr\u00e9sident du conseil d\u2019administration de la coop\u00e9rative, Marc Moffatt.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","class_list":["post-2877","nouvelles","type-nouvelles","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transport r\u00e9gional : la coop Air du Lac-Saint-Jean croit toujours au d\u00e9collage de son projet - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/coop-air-lac-saint-jean-croit-toujours-decollage-projet\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transport r\u00e9gional : la coop Air du Lac-Saint-Jean croit toujours au d\u00e9collage de son projet - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\" \/>\n<meta property=\"og:description\" content=\"Malgr\u00e9 la pand\u00e9mie et l\u2019attente pour le d\u00e9voilement de la strat\u00e9gie en transport a\u00e9rien r\u00e9gional du ministre Fran\u00e7ois Bonnardel, la coop Air du Lac-Saint-Jean a poursuivi son travail afin d\u2019\u00eatre pr\u00eate lorsque les gens pourront voyager plus librement. L\u2019objectif demeure le m\u00eame qu\u2019en novembre 2019, lors de son d\u00e9voilement :...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/coop-air-lac-saint-jean-croit-toujours-decollage-projet\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/coop-air-lac-saint-jean-croit-toujours-decollage-projet\/\",\"url\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/coop-air-lac-saint-jean-croit-toujours-decollage-projet\/\",\"name\":\"Transport r\u00e9gional : la coop Air du Lac-Saint-Jean croit toujours au d\u00e9collage de son projet - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\",\"isPartOf\":{\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/#website\"},\"datePublished\":\"2022-03-02T18:01:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/coop-air-lac-saint-jean-croit-toujours-decollage-projet\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/coop-air-lac-saint-jean-croit-toujours-decollage-projet\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/new\/coop-air-lac-saint-jean-croit-toujours-decollage-projet\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/reseauquebecoisdesaeroports.ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transport r\u00e9gional : la coop Air du Lac-Saint-Jean croit toujours au d\u00e9collage de son projet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/reseauquebecoisdesaeroports.ca\/#website\",\"url\":\"https:\/\/reseauquebecoisdesaeroports.ca\/\",\"name\":\"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/reseauquebecoisdesaeroports.ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transport r\u00e9gional : la coop Air du Lac-Saint-Jean croit toujours au d\u00e9collage de son projet - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/coop-air-lac-saint-jean-croit-toujours-decollage-projet\/","og_locale":"en_US","og_type":"article","og_title":"Transport r\u00e9gional : la coop Air du Lac-Saint-Jean croit toujours au d\u00e9collage de son projet - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","og_description":"Malgr\u00e9 la pand\u00e9mie et l\u2019attente pour le d\u00e9voilement de la strat\u00e9gie en transport a\u00e9rien r\u00e9gional du ministre Fran\u00e7ois Bonnardel, la coop Air du Lac-Saint-Jean a poursuivi son travail afin d\u2019\u00eatre pr\u00eate lorsque les gens pourront voyager plus librement. L\u2019objectif demeure le m\u00eame qu\u2019en novembre 2019, lors de son d\u00e9voilement :...","og_url":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/coop-air-lac-saint-jean-croit-toujours-decollage-projet\/","og_site_name":"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/coop-air-lac-saint-jean-croit-toujours-decollage-projet\/","url":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/coop-air-lac-saint-jean-croit-toujours-decollage-projet\/","name":"Transport r\u00e9gional : la coop Air du Lac-Saint-Jean croit toujours au d\u00e9collage de son projet - R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","isPartOf":{"@id":"https:\/\/reseauquebecoisdesaeroports.ca\/#website"},"datePublished":"2022-03-02T18:01:51+00:00","breadcrumb":{"@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/coop-air-lac-saint-jean-croit-toujours-decollage-projet\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reseauquebecoisdesaeroports.ca\/new\/coop-air-lac-saint-jean-croit-toujours-decollage-projet\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/new\/coop-air-lac-saint-jean-croit-toujours-decollage-projet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/reseauquebecoisdesaeroports.ca\/"},{"@type":"ListItem","position":2,"name":"Transport r\u00e9gional : la coop Air du Lac-Saint-Jean croit toujours au d\u00e9collage de son projet"}]},{"@type":"WebSite","@id":"https:\/\/reseauquebecoisdesaeroports.ca\/#website","url":"https:\/\/reseauquebecoisdesaeroports.ca\/","name":"R\u00e9seau qu\u00e9b\u00e9cois des a\u00e9roports","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reseauquebecoisdesaeroports.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"}]}},"_links":{"self":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/nouvelles\/2877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/nouvelles"}],"about":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/types\/nouvelles"}],"author":[{"embeddable":true,"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/reseauquebecoisdesaeroports.ca\/en\/wp-json\/wp\/v2\/media?parent=2877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}